{"id":33,"count":1,"description":"","link":"https:\/\/www.schoenefeld-parkplatz.de\/blog\/tag\/jugendliche-duerfen-alleine-fliegen\/","name":"Jugendliche d\u00fcrfen alleine fliegen","slug":"jugendliche-duerfen-alleine-fliegen","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.schoenefeld-parkplatz.de\/blog\/wp-json\/wp\/v2\/tags\/33","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.schoenefeld-parkplatz.de\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.schoenefeld-parkplatz.de\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.schoenefeld-parkplatz.de\/blog\/wp-json\/wp\/v2\/posts?tags=33"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}